{"id":9694,"date":"2024-08-30T12:08:27","date_gmt":"2024-08-30T10:08:27","guid":{"rendered":"https:\/\/www.m2act.ch\/?post_type=projects&#038;p=9694"},"modified":"2026-03-16T17:52:18","modified_gmt":"2026-03-16T16:52:18","slug":"theater-chur","status":"publish","type":"projects","link":"https:\/\/www.m2act.ch\/fr\/projects\/theater-chur\/","title":{"rendered":"Theater Chur: Making Peace &#8211; Paix domestique et chemin vers la participation d\u00e9mocratique au Theater Chur"},"content":{"rendered":"\n<p><strong>\u00abMaking Peace\u00bb<\/strong><\/p>\n\n\n\n<p><strong>La paix en interne et l\u2019objectif de la participation d\u00e9mocratique au Theater Chur<\/strong><\/p>\n\n\n\n<p>Des structures d\u2019exploitation modernes doivent \u00eatre mises en place au Theater Chur. La direction et l\u2019\u00e9quipe du th\u00e9\u00e2tre d\u00e9sirent trouver conjointement, pour un positionnement en interne et en externe, des formes de collaboration qui correspondent aux t\u00e2ches et aux besoins actuels d\u2019une institution telle que le Theater Chur et qui soient orient\u00e9es vers l\u2019avenir. Le th\u00e9\u00e2tre doit sortir d\u2019un pass\u00e9 marqu\u00e9 par les conflits et saisir la chance d\u2019un nouveau d\u00e9part en 2024 pour lancer des id\u00e9es.<\/p>\n\n\n\n<p>C\u2019est ici qu\u2019interviennent les r\u00e9flexions sur la recherche artistique sur la paix, qui doivent accompagner le Theater Chur au cours des ann\u00e9es \u00e0 venir, tant sur le plan structurel que sur celui du contenu. Pour porter la paix vers l\u2019ext\u00e9rieur en tant qu\u2019institution culturelle, le th\u00e9\u00e2tre souhaite d\u00e9buter par une r\u00e9flexion sur son propre potentiel de conflits \u00e0 l\u2019\u00e9chelle des \u00eatres humains et de l\u2019exploitation. La vision est d\u2019arriver \u00e0 la paix par l\u2019action. D\u2019abord au sein de l\u2019\u00e9quipe, puis en tant qu\u2019institution et de porter le message \u00e0 l\u2019ext\u00e9rieur, dans la ville, par le biais de projets artistiques, p.&nbsp;ex. une cuisine populaire.<\/p>\n\n\n\n<p>Dans ce processus, les th\u00e8mes qui devront obligatoirement \u00eatre trait\u00e9s par l\u2019\u00e9quipe sont: les voies de communication internes, les interfaces, les processus standard et divergents, la gestion des conflits, la communication non violente, les processus de participation, les mod\u00e8les de hi\u00e9rarchie, des pistes possibles pour les processus d\u00e9cisionnels, la d\u00e9finition de la collaboration.<\/p>\n\n\n\n<p>Cela se fait gr\u00e2ce \u00e0 des \u00e9changes en interne et en externe et \u00e0 l\u2019accompagnement de deux coaches exp\u00e9riment\u00e9es, Anisha Imhasly et Aur\u00e9lie de Lalande. Des outils sont \u00e9labor\u00e9s et peuvent \u00eatre directement utilis\u00e9s au quotidien, dans des situations difficiles. Id\u00e9alement, une bo\u00eete \u00e0 outils correspondante peut \u00e9galement \u00eatre utile \u00e0 d\u2019autres lieux d\u2019accueil de taille moyenne.<\/p>\n\n\n\n    <div id=\"text-shadow-box-block_f65de2e01ada1341ca42d27bcbd65284\" class=\"mod-text-shadow-box\" data-scheme=\"black\">\n\t\t<p><strong>Personnes impliqu\u00e9es<\/strong><\/p>\n<p>Maike Lex, direction du Theater Chur et toute l\u2019\u00e9quipe du Theater Chur<\/p>\n<p>Aur\u00e9lie de Lalande, coach, Berne<\/p>\n<p>Anisha Imhasly, coach, Berne<\/p>\n<p>&nbsp;<\/p>\n<p>Site web: <a href=\"https:\/\/www.theaterchur.ch\/\">Th\u00e9\u00e2tre Chur<\/a><\/p>\n<p>Insta: <a href=\"https:\/\/www.instagram.com\/theaterchur\/\">theaterchur<\/a><\/p>\n    <\/div>\n","protected":false},"featured_media":9701,"template":"","categories":[314],"jahr":[458],"class_list":["post-9694","projects","type-projects","status-publish","has-post-thumbnail","hentry","category-2025-2024-2","jahr-2024-2025"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Theater Chur: Making Peace - Paix domestique et chemin vers la participation d\u00e9mocratique au Theater Chur - M2ACT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.m2act.ch\/fr\/projects\/theater-chur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Theater Chur: Making Peace - Paix domestique et chemin vers la participation d\u00e9mocratique au Theater Chur - M2ACT\" \/>\n<meta property=\"og:description\" content=\"\u00abMaking Peace\u00bb La paix en interne et l\u2019objectif de la participation d\u00e9mocratique au Theater Chur Des structures d\u2019exploitation modernes doivent \u00eatre mises en place au Theater Chur. La direction et l\u2019\u00e9quipe du th\u00e9\u00e2tre d\u00e9sirent trouver conjointement, pour un positionnement en interne et en externe, des formes de collaboration qui correspondent aux t\u00e2ches et aux besoins [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.m2act.ch\/fr\/projects\/theater-chur\/\" \/>\n<meta property=\"og:site_name\" content=\"M2ACT\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-16T16:52:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.m2act.ch\/wp-content\/uploads\/2024\/08\/Theater-Chur.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/projects\\\/theater-chur\\\/\",\"url\":\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/projects\\\/theater-chur\\\/\",\"name\":\"Theater Chur: Making Peace - Paix domestique et chemin vers la participation d\u00e9mocratique au Theater Chur - M2ACT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.m2act.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/projects\\\/theater-chur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/projects\\\/theater-chur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.m2act.ch\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Theater-Chur.jpg\",\"datePublished\":\"2024-08-30T10:08:27+00:00\",\"dateModified\":\"2026-03-16T16:52:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/projects\\\/theater-chur\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/projects\\\/theater-chur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/projects\\\/theater-chur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.m2act.ch\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Theater-Chur.jpg\",\"contentUrl\":\"https:\\\/\\\/www.m2act.ch\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Theater-Chur.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/projects\\\/theater-chur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Theater Chur: Making Peace &#8211; Paix domestique et chemin vers la participation d\u00e9mocratique au Theater Chur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.m2act.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.m2act.ch\\\/en\\\/\",\"name\":\"M2ACT\",\"description\":\"Ein Projekt von Migros Kulturprozent\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.m2act.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Theater Chur: Making Peace - Paix domestique et chemin vers la participation d\u00e9mocratique au Theater Chur - M2ACT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.m2act.ch\/fr\/projects\/theater-chur\/","og_locale":"fr_FR","og_type":"article","og_title":"Theater Chur: Making Peace - Paix domestique et chemin vers la participation d\u00e9mocratique au Theater Chur - M2ACT","og_description":"\u00abMaking Peace\u00bb La paix en interne et l\u2019objectif de la participation d\u00e9mocratique au Theater Chur Des structures d\u2019exploitation modernes doivent \u00eatre mises en place au Theater Chur. La direction et l\u2019\u00e9quipe du th\u00e9\u00e2tre d\u00e9sirent trouver conjointement, pour un positionnement en interne et en externe, des formes de collaboration qui correspondent aux t\u00e2ches et aux besoins [&hellip;]","og_url":"https:\/\/www.m2act.ch\/fr\/projects\/theater-chur\/","og_site_name":"M2ACT","article_modified_time":"2026-03-16T16:52:18+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.m2act.ch\/wp-content\/uploads\/2024\/08\/Theater-Chur.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.m2act.ch\/fr\/projects\/theater-chur\/","url":"https:\/\/www.m2act.ch\/fr\/projects\/theater-chur\/","name":"Theater Chur: Making Peace - Paix domestique et chemin vers la participation d\u00e9mocratique au Theater Chur - M2ACT","isPartOf":{"@id":"https:\/\/www.m2act.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.m2act.ch\/fr\/projects\/theater-chur\/#primaryimage"},"image":{"@id":"https:\/\/www.m2act.ch\/fr\/projects\/theater-chur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.m2act.ch\/wp-content\/uploads\/2024\/08\/Theater-Chur.jpg","datePublished":"2024-08-30T10:08:27+00:00","dateModified":"2026-03-16T16:52:18+00:00","breadcrumb":{"@id":"https:\/\/www.m2act.ch\/fr\/projects\/theater-chur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.m2act.ch\/fr\/projects\/theater-chur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.m2act.ch\/fr\/projects\/theater-chur\/#primaryimage","url":"https:\/\/www.m2act.ch\/wp-content\/uploads\/2024\/08\/Theater-Chur.jpg","contentUrl":"https:\/\/www.m2act.ch\/wp-content\/uploads\/2024\/08\/Theater-Chur.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.m2act.ch\/fr\/projects\/theater-chur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.m2act.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Theater Chur: Making Peace &#8211; Paix domestique et chemin vers la participation d\u00e9mocratique au Theater Chur"}]},{"@type":"WebSite","@id":"https:\/\/www.m2act.ch\/en\/#website","url":"https:\/\/www.m2act.ch\/en\/","name":"M2ACT","description":"Ein Projekt von Migros Kulturprozent","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.m2act.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/projects\/9694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/projects"}],"about":[{"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/types\/projects"}],"version-history":[{"count":2,"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/projects\/9694\/revisions"}],"predecessor-version":[{"id":15303,"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/projects\/9694\/revisions\/15303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/media\/9701"}],"wp:attachment":[{"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/media?parent=9694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/categories?post=9694"},{"taxonomy":"jahr","embeddable":true,"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/jahr?post=9694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}