{"id":7314,"date":"2023-03-29T16:12:30","date_gmt":"2023-03-29T14:12:30","guid":{"rendered":"https:\/\/www.m2act.ch\/?post_type=projects&#038;p=7314"},"modified":"2026-04-02T11:50:42","modified_gmt":"2026-04-02T09:50:42","slug":"tasty-future","status":"publish","type":"projects","link":"https:\/\/www.m2act.ch\/fr\/projects\/tasty-future\/","title":{"rendered":"Tasty Future: Pour une culture alimentaire d\u2019avenir"},"content":{"rendered":"\n<p>Tasty Future donne des impulsions aux institutions du paysage culturel suisse pour r\u00e9orienter leur concept de restauration vers des options plus durables et, si possible, \u00abplant-based\u00bb. Les militant-es zurichois-es \u00e0 l\u2019origine de cette initiative en sont convaincu-es: \u00abcontinuer comme par le pass\u00e9\u00bb ne peut et ne doit \u00eatre une option dans le contexte d\u2019urgence climatique actuel.<\/p>\n\n\n\n<p>Leur objectif est de d\u00e9clencher une dynamique dans le secteur culturel par le biais de nudging cibl\u00e9 aupr\u00e8s des d\u00e9cideurs et des d\u00e9cideuses, de travail de r\u00e9seautage et d\u2019\u00e9change de connaissances. Les mus\u00e9es, th\u00e9\u00e2tres, salles de concert, cin\u00e9mas, festivals et autres institutions culturelles peuvent \u00eatre motiv\u00e9s \u00e0 apporter des modifications concr\u00e8tes et app\u00e9tissantes \u00e0 leur offre de restauration avec le soutien de Tasty Future. Une nouvelle normalit\u00e9 doit s\u2019\u00e9tablir dans le secteur culturel. Une normalit\u00e9 bas\u00e9e sur la production et la consommation de produits v\u00e9g\u00e9taux, bio, locaux et un concept \u00e9vitant le gaspillage alimentaire. Tasty Future donne ainsi un signal fort aux artistes, aux spectateurs et spectatrices et au large public et touche d\u2019autres villes et branches gr\u00e2ce \u00e0 son rayonnement.<\/p>\n\n\n\n<p>Fond\u00e9e en 2021 par Daniel Hellmann et Barbara Ellenberger, Tasty Future se compose aujourd\u2019hui d\u2019une \u00e9quipe comptant un nombre croissant d\u2019activistes alimentaires.<\/p>\n\n\n\n<p>Tasty Future participe aux Journ\u00e9es du Th\u00e9\u00e2tre Suisse 2023 \u00e0 Fribourg avec des ateliers, une exposition permanente et une performance de Daniel Hellmann en Soya the Cow:<\/p>\n\n\n\n    <div id=\"text-shadow-box-block_705bd68b9cab005ef808ec21503b11fd\" class=\"mod-text-shadow-box\" data-scheme=\"white\">\n\t\t<h3>Soya the Cow \u2013 Try Walking in My Hooves<\/h3>\n<p><strong>Promenade urbaine culturelle et mini-concert \u00e0 Fribourg<\/strong><\/p>\n<p>Au cours d\u2019une promenade musicale et philosophique, Soya the Cow guide le public vers des \u00eatres non-humains et questionne ainsi les habitudes visuelles et les \u00e9vidences. C\u2019est un appel ludique \u00e0 repenser le rapport entre les \u00eatres humains et les autres animaux en se basant sur notre animalit\u00e9 commune.<\/p>\n<p>Soya the Cow m\u00eale droits des animaux, activisme climatique, musique et f\u00e9minisme queer en rehaussant le tout d\u2019une bonne dose de drag. L\u2019alter ego de Daniel Hellmann, performeur, musicien et activiste vivant \u00e0 Berlin et \u00e0 Zurich, efface les fronti\u00e8res entre masculin et f\u00e9minin, entre \u00eatre humain et vache et r\u00e9ussit le grand \u00e9cart entre le souhait s\u00e9rieux de changer le monde et une l\u00e9g\u00e8ret\u00e9 pleine d\u2019humour.<\/p>\n<p><a href=\"https:\/\/journees-theatre-suisse.ch\/\" target=\"_blank\" rel=\"noopener\">journees-theatre-suisse.ch<\/a><\/p>\n    <\/div>\n\n\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-md-8\">\n\t\t\t\n\n    <div id=\"text-shadow-box-block_4b2af99fba6bd97ac769784a87a87550\" class=\"mod-text-shadow-box\" data-scheme=\"white\">\n\t\t<p><strong>Personnes impliqu\u00e9es<\/strong><\/p>\n<div>\n<p><strong>Daniel Hellmann<\/strong>, militant et sp\u00e9cialiste en r\u00e9seautage, Zurich<\/p>\n<p><strong>Zo\u00e9 Kilchenmann<\/strong>, militante anti-gaspillage alimentaire et organisatrice, Zurich<strong><\/p>\n<p>Alexandra Gavilano<\/strong>, changeuse de mentalit\u00e9s et militante, Faoug<\/p>\n<\/div>\n    <\/div>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-4\">\n\t\t\t\n\n    <div id=\"text-shadow-box-block_59943baafde3353685cb219fa7f1a884\" class=\"mod-text-shadow-box\" data-scheme=\"black\">\n\t\t<p><b>Plus d&rsquo;informations<\/b><\/p>\n<p><a href=\"http:\/\/www.tastyfuture.ch\" target=\"_blank\" rel=\"noopener\">www.tastyfuture.ch<\/a><\/p>\n<p>Instagram: <a href=\"https:\/\/www.instagram.com\/tasty_future_ch\/\" target=\"_blank\" rel=\"noopener\">tasty_future_ch<\/a><\/p>\n    <\/div>\n\n\t<\/div>\n\n<\/div>\n","protected":false},"featured_media":7408,"template":"","categories":[269],"jahr":[156],"class_list":["post-7314","projects","type-projects","status-publish","has-post-thumbnail","hentry","category-2024-2023-2","jahr-2023-2024"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tasty Future: Pour une culture alimentaire d\u2019avenir - M2ACT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.m2act.ch\/fr\/projects\/tasty-future\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tasty Future: Pour une culture alimentaire d\u2019avenir - M2ACT\" \/>\n<meta property=\"og:description\" content=\"Tasty Future donne des impulsions aux institutions du paysage culturel suisse pour r\u00e9orienter leur concept de restauration vers des options plus durables et, si possible, \u00abplant-based\u00bb. Les militant-es zurichois-es \u00e0 l\u2019origine de cette initiative en sont convaincu-es: \u00abcontinuer comme par le pass\u00e9\u00bb ne peut et ne doit \u00eatre une option dans le contexte d\u2019urgence climatique [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.m2act.ch\/fr\/projects\/tasty-future\/\" \/>\n<meta property=\"og:site_name\" content=\"M2ACT\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-02T09:50:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.m2act.ch\/wp-content\/uploads\/2023\/03\/Tasty-Future-Logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"688\" \/>\n\t<meta property=\"og:image:height\" content=\"688\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/projects\\\/tasty-future\\\/\",\"url\":\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/projects\\\/tasty-future\\\/\",\"name\":\"Tasty Future: Pour une culture alimentaire d\u2019avenir - M2ACT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.m2act.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/projects\\\/tasty-future\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/projects\\\/tasty-future\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.m2act.ch\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Tasty-Future-Logo.png\",\"datePublished\":\"2023-03-29T14:12:30+00:00\",\"dateModified\":\"2026-04-02T09:50:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/projects\\\/tasty-future\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/projects\\\/tasty-future\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/projects\\\/tasty-future\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.m2act.ch\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Tasty-Future-Logo.png\",\"contentUrl\":\"https:\\\/\\\/www.m2act.ch\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Tasty-Future-Logo.png\",\"width\":688,\"height\":688},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/projects\\\/tasty-future\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.m2act.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tasty Future: Pour une culture alimentaire d\u2019avenir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.m2act.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.m2act.ch\\\/en\\\/\",\"name\":\"M2ACT\",\"description\":\"Ein Projekt von Migros Kulturprozent\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.m2act.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tasty Future: Pour une culture alimentaire d\u2019avenir - M2ACT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.m2act.ch\/fr\/projects\/tasty-future\/","og_locale":"fr_FR","og_type":"article","og_title":"Tasty Future: Pour une culture alimentaire d\u2019avenir - M2ACT","og_description":"Tasty Future donne des impulsions aux institutions du paysage culturel suisse pour r\u00e9orienter leur concept de restauration vers des options plus durables et, si possible, \u00abplant-based\u00bb. Les militant-es zurichois-es \u00e0 l\u2019origine de cette initiative en sont convaincu-es: \u00abcontinuer comme par le pass\u00e9\u00bb ne peut et ne doit \u00eatre une option dans le contexte d\u2019urgence climatique [&hellip;]","og_url":"https:\/\/www.m2act.ch\/fr\/projects\/tasty-future\/","og_site_name":"M2ACT","article_modified_time":"2026-04-02T09:50:42+00:00","og_image":[{"width":688,"height":688,"url":"https:\/\/www.m2act.ch\/wp-content\/uploads\/2023\/03\/Tasty-Future-Logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.m2act.ch\/fr\/projects\/tasty-future\/","url":"https:\/\/www.m2act.ch\/fr\/projects\/tasty-future\/","name":"Tasty Future: Pour une culture alimentaire d\u2019avenir - M2ACT","isPartOf":{"@id":"https:\/\/www.m2act.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.m2act.ch\/fr\/projects\/tasty-future\/#primaryimage"},"image":{"@id":"https:\/\/www.m2act.ch\/fr\/projects\/tasty-future\/#primaryimage"},"thumbnailUrl":"https:\/\/www.m2act.ch\/wp-content\/uploads\/2023\/03\/Tasty-Future-Logo.png","datePublished":"2023-03-29T14:12:30+00:00","dateModified":"2026-04-02T09:50:42+00:00","breadcrumb":{"@id":"https:\/\/www.m2act.ch\/fr\/projects\/tasty-future\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.m2act.ch\/fr\/projects\/tasty-future\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.m2act.ch\/fr\/projects\/tasty-future\/#primaryimage","url":"https:\/\/www.m2act.ch\/wp-content\/uploads\/2023\/03\/Tasty-Future-Logo.png","contentUrl":"https:\/\/www.m2act.ch\/wp-content\/uploads\/2023\/03\/Tasty-Future-Logo.png","width":688,"height":688},{"@type":"BreadcrumbList","@id":"https:\/\/www.m2act.ch\/fr\/projects\/tasty-future\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.m2act.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Tasty Future: Pour une culture alimentaire d\u2019avenir"}]},{"@type":"WebSite","@id":"https:\/\/www.m2act.ch\/en\/#website","url":"https:\/\/www.m2act.ch\/en\/","name":"M2ACT","description":"Ein Projekt von Migros Kulturprozent","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.m2act.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/projects\/7314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/projects"}],"about":[{"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/types\/projects"}],"version-history":[{"count":5,"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/projects\/7314\/revisions"}],"predecessor-version":[{"id":14263,"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/projects\/7314\/revisions\/14263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/media\/7408"}],"wp:attachment":[{"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/media?parent=7314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/categories?post=7314"},{"taxonomy":"jahr","embeddable":true,"href":"https:\/\/www.m2act.ch\/fr\/wp-json\/wp\/v2\/jahr?post=7314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}